{"id":27624,"date":"2018-07-19T16:00:04","date_gmt":"2018-07-19T14:00:04","guid":{"rendered":"https:\/\/www.def-shop.com\/magazin\/?p=27624"},"modified":"2018-07-23T13:46:20","modified_gmt":"2018-07-23T11:46:20","slug":"laut-lauter-air-max-95-der-nike-air-max-95-og-is-back","status":"publish","type":"post","link":"https:\/\/www.def-shop.com\/magazin\/laut-lauter-air-max-95-der-nike-air-max-95-og-is-back\/","title":{"rendered":"Laut, Lauter, Air Max 95 &#8211; Der Nike Air Max 95 OG is back"},"content":{"rendered":"<p>Es gibt Sneaker, auf die sich alle einigen k\u00f6nnen. Moderne Klassiker, die immer passen und immer gehen. Und dann gibt es Sneaker, die sind so laut, die muss man wirklich wollen, damit es funktioniert. Die passen nicht zu allen Out\ufb01ts, sind daf\u00fcr aber der absolute Blickfang und eine willkommene Abwechslung zum Standard. Der Nike Air Max 95 war schon immer so ein Schuh und wird es auch immer bleiben. Aber genau deswegen lieben wir das Teil so sehr. Der 95er ist so laut, dass er schon br\u00fcllt. Wahnsinn.<\/p>\n<h2>Bulky Sneakers? Voll im Trend.<\/h2>\n<p><a href=\"https:\/\/www.def-shop.com\/magazin\/wp-content\/uploads\/2018\/07\/BB_Nike-Air-97_m.jpg\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-27645\" src=\"https:\/\/www.def-shop.com\/magazin\/wp-content\/uploads\/2018\/07\/BB_Nike-Air-97_m.jpg\" alt=\"nike air 95 og\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/www.def-shop.com\/magazin\/wp-content\/uploads\/2018\/07\/BB_Nike-Air-97_m.jpg 1500w, https:\/\/www.def-shop.com\/magazin\/wp-content\/uploads\/2018\/07\/BB_Nike-Air-97_m-300x200.jpg 300w, https:\/\/www.def-shop.com\/magazin\/wp-content\/uploads\/2018\/07\/BB_Nike-Air-97_m-768x512.jpg 768w, https:\/\/www.def-shop.com\/magazin\/wp-content\/uploads\/2018\/07\/BB_Nike-Air-97_m-1024x683.jpg 1024w, https:\/\/www.def-shop.com\/magazin\/wp-content\/uploads\/2018\/07\/BB_Nike-Air-97_m-1440x960.jpg 1440w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/><\/a><\/p>\n<p>Der Nike Air Max 95 macht dabei alles andere als einen schlanken Fu\u00df. Das klobige Design ist ebenfalls nicht jedermanns Sache und das mehr als prominente Air-Modul \u2013 das sich durch die gesamte Sohle zieht und auch zum gr\u00f6\u00dften Teil sichtbar ist \u2013 auch nicht. Daf\u00fcr ist der Schuh am Fu\u00df eine absolute Granate und unfassbar bequem. Und darum geht es ja am Ende des Tages. Au\u00dferdem sind solche \u201cbulky\u201d Sneaker oder auch \u201cDad Shoes\u201d gerade sowas von im Trend \u2013 selbst Kanye macht da mit. Wir halten uns aber an das OG Modell, das jetzt endlich wieder im wundersch\u00f6nen \u201cWHITE\/SOLAR RED-GRANITE-DUST\u201d Colourway erh\u00e4ltlich ist.<\/p>\n<p>Die Redaktion ist sich einig: der <a href=\"https:\/\/www.def-shop.com\/nike-air-max-95-og-sneakers-white-solar-red-granite-dust.html\">Nike Air Max 95<\/a> OG ist das Must Have des Sommers.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es gibt Sneaker, auf die sich alle einigen k\u00f6nnen. Moderne Klassiker, die immer passen und immer gehen. Und dann gibt es Sneaker, die sind so laut, die muss man wirklich wollen, damit es funktioniert. Die passen nicht zu allen Out\ufb01ts, sind daf\u00fcr aber der absolute Blickfang und eine willkommene Abwechslung zum Standard. Der Nike Air [&#8230;]<\/p>\n","protected":false},"author":36,"featured_media":27647,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1612,1040,1039],"inspiration_tags":[],"_links":{"self":[{"href":"https:\/\/www.def-shop.com\/magazin\/wp-json\/wp\/v2\/posts\/27624"}],"collection":[{"href":"https:\/\/www.def-shop.com\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.def-shop.com\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.def-shop.com\/magazin\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/www.def-shop.com\/magazin\/wp-json\/wp\/v2\/comments?post=27624"}],"version-history":[{"count":5,"href":"https:\/\/www.def-shop.com\/magazin\/wp-json\/wp\/v2\/posts\/27624\/revisions"}],"predecessor-version":[{"id":27683,"href":"https:\/\/www.def-shop.com\/magazin\/wp-json\/wp\/v2\/posts\/27624\/revisions\/27683"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.def-shop.com\/magazin\/wp-json\/wp\/v2\/media\/27647"}],"wp:attachment":[{"href":"https:\/\/www.def-shop.com\/magazin\/wp-json\/wp\/v2\/media?parent=27624"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.def-shop.com\/magazin\/wp-json\/wp\/v2\/categories?post=27624"},{"taxonomy":"inspiration_tags","embeddable":true,"href":"https:\/\/www.def-shop.com\/magazin\/wp-json\/wp\/v2\/inspiration_tags?post=27624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}